{"id":93,"date":"2024-04-25T13:48:13","date_gmt":"2024-04-25T13:48:13","guid":{"rendered":"https:\/\/zulf.sk\/?page_id=93"},"modified":"2024-04-25T13:48:13","modified_gmt":"2024-04-25T13:48:13","slug":"refund-policy","status":"publish","type":"page","link":"https:\/\/zulf.sk\/it\/refund-policy\/","title":{"rendered":"Politica di rimborso"},"content":{"rendered":"<p>Noi di Zulf s.r.o. ci impegniamo a fornire un servizio clienti eccellente. Tuttavia, siamo consapevoli che possono verificarsi casi in cui \u00e8 necessario un rimborso. Si prega di leggere la nostra politica di rimborso qui di seguito:<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Condizioni per il rimborso<\/h2>\n\n\n\n<p>Tutti i rimborsi sono possibili solo entro 30 giorni di calendario dalla data del trasferimento di denaro. Gli ordini sono rimborsabili fino all'inoltro del pagamento a qualsiasi piattaforma o rete pubblicitaria e al lancio della campagna pubblicitaria.&nbsp;<\/p>\n\n\n\n<p>Vengono inoltre elaborati rimborsi per ordini errati (ad esempio, pagamenti duplicati o pagamenti in eccesso).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Avvio di un rimborso<\/h2>\n\n\n\n<p>Per avviare un rimborso, inviare una richiesta al nostro indirizzo e-mail <strong>info@zulf.sk <\/strong>e allegare la prova che la richiesta di rimborso \u00e8 ammissibile. Anche se il vostro caso non soddisfa le condizioni, potete comunque richiedere un rimborso. Esamineremo la vostra richiesta e vi forniremo una decisione entro 5 giorni lavorativi.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Rimborsi approvati<\/h2>\n\n\n\n<p>Se la richiesta di rimborso viene approvata ed entrambe le parti concordano sull'importo, il denaro verr\u00e0 rimborsato utilizzando lo stesso metodo di pagamento. Si prega di notare che il metodo di pagamento non pu\u00f2 essere cambiato in nessuna condizione.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Contatto<\/h2>\n\n\n\n<p>Potete contattare il nostro team utilizzando uno dei seguenti metodi:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>E-mail:<\/strong> <a href=\"mailto:info@zulf.sk\">info@zulf.sk<\/a><\/li>\n\n\n\n<li><strong>Telefono:<\/strong> <a href=\"tel:+421233070456\">+421233070456<\/a><\/li>\n\n\n\n<li><strong>Sito web:<\/strong> <a href=\"https:\/\/zulf.sk\/it\/\">www.zulf.sk<\/a><\/li>\n<\/ul>\n\n\n\n<p>Se avete domande o avete bisogno di ulteriore assistenza in merito alla nostra politica di rimborso, non esitate a contattarci.<\/p>","protected":false},"excerpt":{"rendered":"<p>Noi di Zulf s.r.o. ci impegniamo a fornire un servizio clienti eccellente. Tuttavia, siamo consapevoli che possono verificarsi casi in cui \u00e8 necessario un rimborso. Si prega di leggere la nostra politica di rimborso qui di seguito: Condizioni di rimborso Tutti i rimborsi sono possibili solo entro 30 giorni di calendario dalla data del trasferimento di denaro. Gli ordini sono rimborsabili fino al pagamento [...]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-pages\/policy.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-93","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Refund Policy - zulf.sk<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zulf.sk\/it\/refund-policy\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Refund Policy - zulf.sk\" \/>\n<meta property=\"og:description\" content=\"At Zulf s.r.o., we are committed to providing excellent customer service. However, we understand that there may be instances where a refund is necessary. Please read our refund policy below: Conditions for Refund All refunds are possible only within 30 calendar days from the date of the money transfer. Orders are refundable until payment is [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zulf.sk\/it\/refund-policy\/\" \/>\n<meta property=\"og:site_name\" content=\"zulf.sk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/zulf.sk\/refund-policy\/\",\"url\":\"https:\/\/zulf.sk\/refund-policy\/\",\"name\":\"Refund Policy - zulf.sk\",\"isPartOf\":{\"@id\":\"https:\/\/zulf.sk\/#website\"},\"datePublished\":\"2024-04-25T13:48:13+00:00\",\"dateModified\":\"2024-04-25T13:48:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/zulf.sk\/refund-policy\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/zulf.sk\/refund-policy\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/zulf.sk\/refund-policy\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/zulf.sk\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Refund Policy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/zulf.sk\/#website\",\"url\":\"https:\/\/zulf.sk\/\",\"name\":\"zulf.sk\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/zulf.sk\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/zulf.sk\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/zulf.sk\/#organization\",\"name\":\"zulf.sk\",\"url\":\"https:\/\/zulf.sk\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/zulf.sk\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/zulf.sk\/wp-content\/uploads\/2024\/04\/zulf_logo.svg\",\"contentUrl\":\"https:\/\/zulf.sk\/wp-content\/uploads\/2024\/04\/zulf_logo.svg\",\"width\":128,\"height\":40,\"caption\":\"zulf.sk\"},\"image\":{\"@id\":\"https:\/\/zulf.sk\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Refund Policy - zulf.sk","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zulf.sk\/it\/refund-policy\/","og_locale":"it_IT","og_type":"article","og_title":"Refund Policy - zulf.sk","og_description":"At Zulf s.r.o., we are committed to providing excellent customer service. However, we understand that there may be instances where a refund is necessary. Please read our refund policy below: Conditions for Refund All refunds are possible only within 30 calendar days from the date of the money transfer. Orders are refundable until payment is [&hellip;]","og_url":"https:\/\/zulf.sk\/it\/refund-policy\/","og_site_name":"zulf.sk","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zulf.sk\/refund-policy\/","url":"https:\/\/zulf.sk\/refund-policy\/","name":"Refund Policy - zulf.sk","isPartOf":{"@id":"https:\/\/zulf.sk\/#website"},"datePublished":"2024-04-25T13:48:13+00:00","dateModified":"2024-04-25T13:48:13+00:00","breadcrumb":{"@id":"https:\/\/zulf.sk\/refund-policy\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zulf.sk\/refund-policy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/zulf.sk\/refund-policy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/zulf.sk\/"},{"@type":"ListItem","position":2,"name":"Refund Policy"}]},{"@type":"WebSite","@id":"https:\/\/zulf.sk\/#website","url":"https:\/\/zulf.sk\/","name":"zulf.sk","description":"","publisher":{"@id":"https:\/\/zulf.sk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zulf.sk\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/zulf.sk\/#organization","name":"zulf.sk","url":"https:\/\/zulf.sk\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/zulf.sk\/#\/schema\/logo\/image\/","url":"https:\/\/zulf.sk\/wp-content\/uploads\/2024\/04\/zulf_logo.svg","contentUrl":"https:\/\/zulf.sk\/wp-content\/uploads\/2024\/04\/zulf_logo.svg","width":128,"height":40,"caption":"zulf.sk"},"image":{"@id":"https:\/\/zulf.sk\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/zulf.sk\/it\/wp-json\/wp\/v2\/pages\/93","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zulf.sk\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/zulf.sk\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/zulf.sk\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zulf.sk\/it\/wp-json\/wp\/v2\/comments?post=93"}],"version-history":[{"count":1,"href":"https:\/\/zulf.sk\/it\/wp-json\/wp\/v2\/pages\/93\/revisions"}],"predecessor-version":[{"id":94,"href":"https:\/\/zulf.sk\/it\/wp-json\/wp\/v2\/pages\/93\/revisions\/94"}],"wp:attachment":[{"href":"https:\/\/zulf.sk\/it\/wp-json\/wp\/v2\/media?parent=93"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}